{"id":1469,"date":"2020-10-28T12:04:00","date_gmt":"2020-10-28T11:04:00","guid":{"rendered":"https:\/\/www.opengreen.it\/?p=1469"},"modified":"2020-11-16T09:16:27","modified_gmt":"2020-11-16T08:16:27","slug":"prodotti-per-agricoltura-biologica","status":"publish","type":"post","link":"https:\/\/www.opengreen.it\/it\/prodotti-per-agricoltura-biologica\/","title":{"rendered":"Microelementi in agricoltura"},"content":{"rendered":"\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\" style=\"flex-basis:66.66%\">\n<div id=\"intro\">\n<p>I <strong>microelementi sono delle sostanze nutritive utilizzate in agricoltura<\/strong>, che vengono assorbite dal suolo in modo ridotto e lento, per questo motivo rappresentano un elemento di importanza rilevante per la fisiologia degli organismi vegetali: entrano nella costituzione di enzimi e coenzimi fungendo da veri e propri catalizzatori per le funzioni vitali delle piante. Tutti i <strong>microelemen<\/strong>ti hanno un ruolo essenziale nei processi che avvengono durante la vita e la crescita delle agricolture, un uso eccessivo o ridotto pu&ograve; creare diversi tipi di squilibri che possono indurre anche delle fisiopatie.<\/p>\n<\/div>\n\n\n\n<h3 id=\"testo1\">Come riconoscere le carenze o gli eccessi di microelementi<\/h3>\n<div id=\"attachment_1405\" style=\"width: 1135px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-1405\" loading=\"lazy\" class=\"wp-image-1405 size-full\" src=\"https:\/\/www.opengreen.it\/wp-content\/uploads\/2020\/10\/microelementi_in_agricoltura_02.png\" alt=\"\" width=\"1125\" height=\"750\"><p id=\"caption-attachment-1405\" class=\"wp-caption-text\">Riconoscere le carenze o gli eccessi di microelementi<\/p><\/div>\n<p><strong>I microelementi<\/strong> sono sostanze che svolgono una funzione fondamentale per il benessere della pianta, proprio per questo motivo &egrave; importante riconoscere quali sono i sintomi che manifestano le piante, per determinare se ci siano <strong>carenze o eccess<\/strong>i nel loro utilizzo: un fattore che balza immediatamente all&rsquo;occhio pu&ograve; essere una colorazione anomala delle foglie, come per esempio ingiallimenti che non sono causati da aridit&agrave; o arrossimento, che indica una carenza di determinati microelementi; un altro fattore pu&ograve; essere anche la mancata crescita delle piante, che si &egrave; arrestata a causa di un <strong>uso squilibrato di microelementi<\/strong>.<\/p>\n<a class=\"art2f_btn-cta\" href=\"https:\/\/www.opengreen.it\/contatti\/\">contattaci<\/a>\n\n\n\n<h3 id=\"testo2\">Principali microelementi nel suolo<\/h3>\n<div id=\"attachment_1407\" style=\"width: 1010px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-1407\" loading=\"lazy\" class=\"wp-image-1407 size-full\" src=\"https:\/\/www.opengreen.it\/wp-content\/uploads\/2020\/10\/microelementi_in_agricoltura_03.png\" alt=\"\" width=\"1000\" height=\"750\"><p id=\"caption-attachment-1407\" class=\"wp-caption-text\">Principali microelementi nel suolo<\/p><\/div>\n<p>I Principali microelementi presenti nel suolo e utili per le coltivazioni sono:<\/p>\n<ul>\n<li>Calcio: indispensabile per la crescita delle piante orticole, l&rsquo;eccesso si nota in presenza di terreno calcareo, mentre la carenza si manifesta con l&rsquo;ingiallimento delle foglie.<\/li>\n<li>Ferro: in caso di carenza si pu&ograve; manifestare in un ingiallimento nella nervatura delle foglie.<\/li>\n<li>Magnesio: la sua assenza &egrave; molto rara, infatti lo si trova in diversi tipi di concimi<\/li>\n<li>Manganese: questo elemento si assorbe meglio quando il pH del terreno &egrave; basso.<\/li>\n<li>Zinco: &egrave; raro che possa mancare nel terreno, se vi sono carenze sono dovute a difficolt&agrave; di assorbimento delle piante.<\/li>\n<li>Rame: un eccesso di rame pu&ograve; limitare l&rsquo;assorbimento di ferro da parte delle piante, quindi una clorosi ferrica<\/li>\n<li>Boro: gli eccessi sono particolarmente nocivi, in genere il terreno ne &egrave; abbastanza ricco.<\/li>\n<li>Silicio: fondamentale per le piante in quanto aiuta le cellule ad essere pi&ugrave; resistenti.<\/li>\n<\/ul>\n<a class=\"art2f_btn-cta\" href=\"https:\/\/www.opengreen.it\/contatti\/\">contattaci<\/a>\n<\/div>\n\n\n\n<div class=\"wp-block-column\" style=\"flex-basis:33.33%\">\n<ul>\n<li><a href=\"#intro\">intro<\/a><\/li>\n<li><a href=\"#testo1\">Come riconoscere le carenze o gli eccessi di microelementi<\/a><\/li>\n<li><a href=\"#testo2\">Principali microelementi nel suolo<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>I microelementi sono delle sostanze nutritive utilizzate in agricoltura, che vengono assorbite dal suolo in modo ridotto e lento, per questo motivo rappresentano un elemento di importanza rilevante per la fisiologia degli organismi vegetali: entrano nella costituzione di enzimi e coenzimi fungendo da veri e propri catalizzatori per le funzioni vitali delle piante. Tutti i [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":1479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[44],"tags":[],"_links":{"self":[{"href":"https:\/\/www.opengreen.it\/it\/wp-json\/wp\/v2\/posts\/1469"}],"collection":[{"href":"https:\/\/www.opengreen.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opengreen.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opengreen.it\/it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opengreen.it\/it\/wp-json\/wp\/v2\/comments?post=1469"}],"version-history":[{"count":0,"href":"https:\/\/www.opengreen.it\/it\/wp-json\/wp\/v2\/posts\/1469\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opengreen.it\/it\/wp-json\/wp\/v2\/media\/1479"}],"wp:attachment":[{"href":"https:\/\/www.opengreen.it\/it\/wp-json\/wp\/v2\/media?parent=1469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opengreen.it\/it\/wp-json\/wp\/v2\/categories?post=1469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opengreen.it\/it\/wp-json\/wp\/v2\/tags?post=1469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}